{"id":1786,"date":"2022-04-05T11:08:32","date_gmt":"2022-04-05T09:08:32","guid":{"rendered":"https:\/\/tst.rkmzf.ch\/?p=1786"},"modified":"2022-04-05T11:08:32","modified_gmt":"2022-04-05T09:08:32","slug":"combler-les-lacunes-dans-la-protection-de-la-population-et-dans-larmee","status":"publish","type":"post","link":"https:\/\/tst.rkmzf.ch\/fr\/combler-les-lacunes-dans-la-protection-de-la-population-et-dans-larmee\/","title":{"rendered":"Combler les lacunes dans la protection de la population et dans l\u2019arm\u00e9e"},"content":{"rendered":"<p>Vu la guerre en Ukraine, la Conf\u00e9rence gouvernementale des affaires militaires, de la protection civile et des sapeurs-pompiers (CG MPS) constate que les d\u00e9fis en mati\u00e8re de politique de s\u00e9curit\u00e9 pour la Suisse apparaissent encore notablement plus manifestement que c\u2019\u00e9tait le cas jusqu\u2019\u00e0 ce jour. Les lacunes existantes doivent par cons\u00e9quent \u00eatre \u00e9num\u00e9r\u00e9es et combl\u00e9es.<br \/>\nLa guerre en Ukraine confronte la protection de la population de la Suisse \u00e0 de nouveaux d\u00e9fis. Ainsi, les projets-cl\u00e9s portant sur la transmission s\u00e9curis\u00e9e des donn\u00e9es doivent \u00eatre r\u00e9alis\u00e9s le plus rapidement possible. La modernisation et le d\u00e9veloppement des abris pour la population, des ouvrages prot\u00e9g\u00e9s de la protection civile et des installations sanitaires prot\u00e9g\u00e9es doivent \u00eatre r\u00e9examin\u00e9s. Le profil de prestations de la protection civile doit \u00e9galement \u00eatre r\u00e9\u00e9valu\u00e9. Il en va notamment de l\u2019appui \u00e0 la population et de la prise en charge de cette derni\u00e8re en cas d\u2019occupation des abris, ainsi que de la r\u00e9introduction d\u2019un service sanitaire charg\u00e9 de l\u2019exploitation des installations prot\u00e9g\u00e9es. Les effectifs, les structures de conduite et les processus d\u00e9cisionnels de la protection civile doivent \u00e9galement faire l\u2019objet d\u2019une nouvelle appr\u00e9ciation sur la base des besoins d\u00e9coulant d\u2019un conflit arm\u00e9. De son c\u00f4t\u00e9, l\u2019arm\u00e9e doit accorder une importance accrue \u00e0 sa mission-cl\u00e9 qu\u2019est la d\u00e9fense. Elle doit \u00eatre \u00e9quip\u00e9e en cons\u00e9quence. Cet \u00e9quipement porte non seulement sur l\u2019indispensable protection de l\u2019espace a\u00e9rien avec des avions de combat du type F-35, mais aussi sur la capacit\u00e9 \u00e0 tenir sur la dur\u00e9e, avec des r\u00e9serves de personnel et de mat\u00e9riel suffisantes. Tous ces th\u00e8mes seront au c\u0153ur de la conf\u00e9rence annuelle de cette ann\u00e9e de la CG MPS. Cette assembl\u00e9e aura lieu le 6 mai 2022 \u00e0 Soleure, en pr\u00e9sence de la conseill\u00e8re f\u00e9d\u00e9rale Viola Amherd et du commandant de corps Thomas S\u00fcssli.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vu la guerre en Ukraine, la Conf\u00e9rence gouvernementale des affaires militaires, de la protection civile et des sapeurs-pompiers (CG MPS) constate que les d\u00e9fis en mati\u00e8re de politique de s\u00e9curit\u00e9 pour la Suisse apparaissent encore notablement plus manifestement que c\u2019\u00e9tait le cas jusqu\u2019\u00e0 ce jour. Les lacunes existantes doivent par cons\u00e9quent \u00eatre \u00e9num\u00e9r\u00e9es et combl\u00e9es. [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-1786","post","type-post","status-publish","format-standard","hentry","category-non-classifiee"],"_links":{"self":[{"href":"https:\/\/tst.rkmzf.ch\/fr\/wp-json\/wp\/v2\/posts\/1786","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tst.rkmzf.ch\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tst.rkmzf.ch\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tst.rkmzf.ch\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/tst.rkmzf.ch\/fr\/wp-json\/wp\/v2\/comments?post=1786"}],"version-history":[{"count":1,"href":"https:\/\/tst.rkmzf.ch\/fr\/wp-json\/wp\/v2\/posts\/1786\/revisions"}],"predecessor-version":[{"id":1787,"href":"https:\/\/tst.rkmzf.ch\/fr\/wp-json\/wp\/v2\/posts\/1786\/revisions\/1787"}],"wp:attachment":[{"href":"https:\/\/tst.rkmzf.ch\/fr\/wp-json\/wp\/v2\/media?parent=1786"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tst.rkmzf.ch\/fr\/wp-json\/wp\/v2\/categories?post=1786"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tst.rkmzf.ch\/fr\/wp-json\/wp\/v2\/tags?post=1786"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}