{"id":510,"date":"2017-02-02T15:37:08","date_gmt":"2017-02-02T14:37:08","guid":{"rendered":"https:\/\/tst.rkmzf.ch\/fr\/?p=510"},"modified":"2017-02-02T15:37:08","modified_gmt":"2017-02-02T14:37:08","slug":"concordat-intercantonal-concernant-lassurance-tremblements-de-terre","status":"publish","type":"post","link":"https:\/\/tst.rkmzf.ch\/fr\/concordat-intercantonal-concernant-lassurance-tremblements-de-terre\/","title":{"rendered":"Concordat intercantonal concernant l\u2019assurance tremblements de terre"},"content":{"rendered":"<p>Le 29 janvier 2016, la Commission de l&rsquo;environnement, de l&rsquo;am\u00e9nagement du territoire et de l&rsquo;\u00e9nergie du Conseil des Etats (\u00a0CEATE-E\u00a0) a contact\u00e9 la Conf\u00e9rence des gouvernements cantonaux (\u00a0CdC\u00a0) en relation avec la question de l\u2019introduction d\u2019une assurance tremblements de terre obligatoire au niveau national. La Commission a notamment pri\u00e9 la CdC de clarifier dans quelle mesure les cantons souhaitent introduire une assurance tremblements de terre obligatoire en Suisse.<\/p>\n<p>Pour donner suite \u00e0 cette demande, la CdC a proc\u00e9d\u00e9 \u00e0 une enqu\u00eate aupr\u00e8s des cantons, du 11 mars au 27 mai 2016. 16 cantons se sont exprim\u00e9s en faveur de l\u2019introduction d\u2019une assurance tremblements de terre obligatoire (\u00a0ZH, BE, SZ, OW, NW, GL, FR, SO, BS, BL, SH, SG, VD, VS, GE, JU\u00a0). 6 cantons se sont exprim\u00e9s n\u00e9gativement (\u00a0LU, ZG, AR, AI, AG, TG\u00a0). 17 cantons se sont exprim\u00e9s en faveur d\u2019un concordat pour la r\u00e9alisation d\u2019une assurance tremblements de terre obligatoire (\u00a0BE, LU, OW, NW, GL, FR, SO, BS, BL, SH, AI, SG, GR, AG, VD, VS, JU\u00a0). Toutefois, la plupart des cantons favorables associent \u00e0 cette solution toute une s\u00e9rie de conditions. 6 cantons sont contre la r\u00e9alisation sous la forme d\u2019un concordat (\u00a0ZH, SZ, ZG, AR, TG, GE\u00a0).<\/p>\n<p>Le 26 septembre 2016, la CEATE-E a inform\u00e9 la CdC qu\u2019\u00e0 son avis, l\u2019introduction d\u2019une nouvelle comp\u00e9tence au niveau de la Conf\u00e9d\u00e9ration ne constitue pas une solution ad\u00e9quate. La Commission restant cependant d\u2019avis que l\u2019introduction d\u2019une assurance tremblements de terre au niveau national est indispensable, elle est favorable \u00e0 la cr\u00e9ation d\u2019un concordat intercantonal comme unique solution envisageable. De cette mani\u00e8re, les comp\u00e9tences cantonales peuvent \u00eatre sauvegard\u00e9es et il n\u2019est pas n\u00e9cessaire de proc\u00e9der \u00e0 un amendement de la Constitution, chose relativement compliqu\u00e9e. Par cons\u00e9quent, la CEATE-E a enjoint la CdC d\u2019oeuvrer \u00e0 la cr\u00e9ation d\u2019un concordat intercantonal jusqu\u2019\u00e0 la mi-2017.<\/p>\n<p>Le 10 octobre 2016, la CdC a \u00e9crit \u00e0 la CG MPS pour lui transmettre la demande de la CEATE-E. La CG MPS a inscrit cette question \u00e0 l\u2019ordre du jour de son assembl\u00e9e pl\u00e9ni\u00e8re du 17 novembre 2016. A cette assembl\u00e9e, il a \u00e9t\u00e9 d\u00e9cid\u00e9 d\u2019examiner la cr\u00e9ation d\u2019un \u00ab\u00a0concordat intercantonal pour une assurance tremblements de terre\u00a0\u00bb et de pr\u00e9senter les r\u00e9sultats de ces travaux \u00e0 l\u2019assembl\u00e9e pl\u00e9ni\u00e8re du 19 mai 2017.<\/p>\n<p>Le 25 novembre 2016, le pr\u00e9sident de la CG MPS a charg\u00e9 le secr\u00e9taire g\u00e9n\u00e9ral de la CG MPS d\u2019instituer un groupe de travail \u00ab\u00a0concordat intercantonal pour une assurance tremblements de terre\u00a0\u00bb. Une premi\u00e8re s\u00e9ance a ensuite eu lieu le 20 d\u00e9cembre 2016.<a href=\"#_ftn1\" name=\"_ftnref1\"><sup><sup>[1]<\/sup><\/sup><\/a> Cette s\u00e9ance a servi \u00e0 fixer la composition du groupe de travail, la teneur des travaux ainsi que les \u00e9tapes. Selon ce plan, les membres de la CG MPS recevront d\u2019ici au 24 avril 2017 une base d\u00e9cisionnelle, sous la forme d\u2019un rapport pr\u00e9sentant les grands axes d\u2019un concordat. L\u2019assembl\u00e9e pl\u00e9ni\u00e8re prendra une d\u00e9cision au sujet de la suite des activit\u00e9s le 19 mai 2017 \u00e0 Lugano.<\/p>\n<p>Teneur du rapport \u00abconcordat intercantonal pour une assurance tremblements de terre\u00a0: base d\u00e9cisionnelle pour la suite des activit\u00e9s\u00bb<\/p>\n<ol>\n<li>Bases (\u00a0situation en mati\u00e8re de dangers, \u00e9tendue des dommages, cons\u00e9quences pour la population\u00a0)<\/li>\n<li>Solution d\u2019assurance (\u00a0solution f\u00e9d\u00e9rale avec obligation cantonale, primes basses et int\u00e9gration de la Conf\u00e9d\u00e9ration\u00a0)<\/li>\n<li>Concordat (\u00a0donn\u00e9es principales, processus\u00a0)<\/li>\n<li>Int\u00e9gration de la Conf\u00e9d\u00e9ration (\u00a0aspects juridiques, implications politiques\u00a0)<\/li>\n<li>Recommandations<\/li>\n<\/ol>\n<p>Ce plan d\u2019activit\u00e9s a \u00e9t\u00e9 approuv\u00e9 par le comit\u00e9 de la CG MPS lors de sa s\u00e9ance du 4 janvier 2017, \u00e0 Interlaken.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le 29 janvier 2016, la Commission de l&rsquo;environnement, de l&rsquo;am\u00e9nagement du territoire et de l&rsquo;\u00e9nergie du Conseil des Etats (\u00a0CEATE-E\u00a0) a contact\u00e9 la Conf\u00e9rence des gouvernements cantonaux (\u00a0CdC\u00a0) en relation avec la question de l\u2019introduction d\u2019une assurance tremblements de terre obligatoire au niveau national. La Commission a notamment pri\u00e9 la CdC de clarifier dans quelle [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-510","post","type-post","status-publish","format-standard","hentry","category-non-classifiee"],"_links":{"self":[{"href":"https:\/\/tst.rkmzf.ch\/fr\/wp-json\/wp\/v2\/posts\/510","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tst.rkmzf.ch\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tst.rkmzf.ch\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tst.rkmzf.ch\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/tst.rkmzf.ch\/fr\/wp-json\/wp\/v2\/comments?post=510"}],"version-history":[{"count":1,"href":"https:\/\/tst.rkmzf.ch\/fr\/wp-json\/wp\/v2\/posts\/510\/revisions"}],"predecessor-version":[{"id":511,"href":"https:\/\/tst.rkmzf.ch\/fr\/wp-json\/wp\/v2\/posts\/510\/revisions\/511"}],"wp:attachment":[{"href":"https:\/\/tst.rkmzf.ch\/fr\/wp-json\/wp\/v2\/media?parent=510"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tst.rkmzf.ch\/fr\/wp-json\/wp\/v2\/categories?post=510"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tst.rkmzf.ch\/fr\/wp-json\/wp\/v2\/tags?post=510"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}