{"id":873,"date":"2018-05-09T10:03:41","date_gmt":"2018-05-09T08:03:41","guid":{"rendered":"https:\/\/tst.rkmzf.ch\/?p=873"},"modified":"2018-05-09T10:03:41","modified_gmt":"2018-05-09T08:03:41","slug":"defis-en-relation-avec-larmee-et-la-protection-civile","status":"publish","type":"post","link":"https:\/\/tst.rkmzf.ch\/fr\/defis-en-relation-avec-larmee-et-la-protection-civile\/","title":{"rendered":"D\u00e9fis en relation avec l\u2019arm\u00e9e et la protection civile"},"content":{"rendered":"<p>L\u2019assembl\u00e9e annuelle de la Conf\u00e9rence gouvernementale intercantonale des affaires militaires, de la protection civile et des sapeurs-pompiers (CG MPS)\u00a0du 4 mai 2018 \u00e0 l&rsquo; Abbaye b\u00e9n\u00e9dictine de Disentis a notamment \u00e9t\u00e9 consacr\u00e9e \u00e0 la prise de d\u00e9cision au sujet de l\u2019introduction d\u2019une journ\u00e9e d\u2019information obligatoire pour les Suissesses et \u00e0 la clarification de t\u00e2ches en relation avec l\u2019introduction de la mobilisation, dans le cadre de la poursuite du d\u00e9veloppement de l\u2019arm\u00e9e (DEVA). Par ailleurs, des mesures propres \u00e0 augmenter les effectifs de la protection civile ainsi que la cr\u00e9ation d\u2019un service sanitaire dans la protection civile ont \u00e9t\u00e9 examin\u00e9es en pr\u00e9sence du conseiller f\u00e9d\u00e9ral Guy Parmelin, chef du DDPS.<\/p>\n<p>R\u00e9unis \u00e0 Disentis pour leur conf\u00e9rence annuelle, les membres des gouvernements cantonaux comp\u00e9tents pour les affaires militaires, la protection civile et le domaine des sapeurs-pompiers ont pris une d\u00e9cision au sujet de la poursuite des activit\u00e9s en relation avec la journ\u00e9e d\u2019information. Un groupe de travail \u00e0 la large assise avait examin\u00e9 plusieurs options depuis le mois de mai 2017, l\u2019une d\u2019entre elles \u00e9tant l\u2019introduction d\u2019une journ\u00e9e d\u2019information obligatoire pour les Suissesses. Selon un avis de droit externe, une telle mesure n\u00e9cessiterait un amendement de la Constitution, raison pour laquelle la CG MPS a d\u00e9cid\u00e9 de renoncer \u00e0 l\u2019introduction d\u2019une telle obligation. En lieu et place, l\u2019option retenue pr\u00e9voit que tous les cantons auront le devoir d\u2019inviter \u00e0 la journ\u00e9e d\u2019information les Suissesses, qui ne sont pas astreintes au service. La participation \u00e0 cette journ\u00e9e, qui restera facultative, devrait constituer une convocation contraignante des autorit\u00e9s pour r\u00e9duire les inconv\u00e9nients de la participation (par exemple une r\u00e9duction du salaire). La concr\u00e9tisation de ces mesures n\u00e9cessite maintenant d\u2019adapter le Code des obligations et la Loi sur les allocations pour perte de gain.<\/p>\n<p>L\u2019Ordonnance sur la mobilisation de l\u2019arm\u00e9e (OMob) r\u00e8gle les t\u00e2ches et les devoirs des cantons, des communes et des priv\u00e9s lors de la mise de piquet et de la mobilisation. Elle repose sur les articles correspondants de la Loi sur l\u2019arm\u00e9e et l\u2019administration militaire (LAAM). Jusqu\u2019\u00e0 ce jour, cette loi ne traite pas de la mobilisation en vue des services d\u2019assistance, alors que ces derniers sont importants pour les cantons puisqu\u2019ils leur permettent de recourir au soutien de l\u2019arm\u00e9e pour faire face \u00e0 des catastrophes ou \u00e0 des pics de besoins, ainsi que pour accomplir des t\u00e2ches pour lesquelles les moyens personnels ou mat\u00e9riels disponibles ne suffisent pas. L\u2019OMob actuelle ne fixe pas de responsabilit\u00e9s pr\u00e9cises ni de processus concrets concernant la mobilisation. Les bases n\u00e9cessaires \u00e0 cet effet ont maintenant pu \u00eatre \u00e9labor\u00e9es sous la direction de la CG MPS comme solution transitoire, pour combler les lacunes en attendant l\u2019adaptation de la LAAM et de l\u2019OMob. Simultan\u00e9ment, les t\u00e2ches des cantons et des communes en cas de mobilisation ont \u00e9t\u00e9 d\u00e9finies. La mise en \u0153uvre de ces mesures devrait \u00eatre termin\u00e9e \u00e0 la fin 2020.<\/p>\n<p>La baisse des effectifs de la protection civile est probl\u00e9matique. Si 8&rsquo;117 personnes ont encore pu \u00eatre recrut\u00e9es pour la protection civile en 2010, elles n\u2019\u00e9taient plus que 4&rsquo;805 en 2017. Les motifs de cette diminution ne sont pas encore enti\u00e8rement clarifi\u00e9s. Des adaptations du syst\u00e8me d\u2019obligation de servir seront toutefois vraisemblablement in\u00e9luctables \u00e0 long terme comme solution durable. En novembre 2016 d\u00e9j\u00e0, la CG MPS avait recommand\u00e9, en relation avec le rapport du groupe d\u2019\u00e9tude du syst\u00e8me d\u2019obligation de servir, d\u2019approfondir non seulement le \u00abmod\u00e8le norv\u00e9gien\u00bb mais aussi le mod\u00e8le \u00abobligation de servir dans la s\u00e9curit\u00e9\u00bb. Ce dernier mod\u00e8le pourrait simplifier le syst\u00e8me actuel en regroupant la protection civile et le service civil au sein d\u2019une \u00abprotection en cas de catastrophe\u00bb. Le 28 juin 2017, le Conseil f\u00e9d\u00e9ral a d\u00e9cid\u00e9 de se concentrer sur le \u00abmod\u00e8le norv\u00e9gien\u00bb, sans tenir compte de la recommandation des cantons. Ce mod\u00e8le pr\u00e9voit notamment l\u2019introduction du service militaire et du service de protection obligatoire pour les Suissesses. Par cons\u00e9quent, \u00e0 Disentis, la CG MPS a demand\u00e9 du Conseil f\u00e9d\u00e9ral qu\u2019il examine le mod\u00e8le \u00abobligation de servir dans la s\u00e9curit\u00e9\u00bb dans le cadre des activit\u00e9s du groupe de travail \u00abMandats subs\u00e9quents relatifs au d\u00e9veloppement du syst\u00e8me d\u2019obligation de servir\u00bb.<\/p>\n<p>L\u2019exploitation de 100 centres sanitaires prot\u00e9g\u00e9s pour soutenir le domaine de la sant\u00e9 pendant une p\u00e9riode prolong\u00e9e en cas de catastrophe n\u00e9cessite approximativement 8\u2019000 miliciens suppl\u00e9mentaires. De l\u2019avis de l\u2019Office f\u00e9d\u00e9ral de la protection de la population (OFPP), cette t\u00e2che ne peut \u00eatre accomplie que par la protection civile, comme instrument strat\u00e9gique des cantons pour tenir sur la dur\u00e9e. La CG MPS partage cette opinion, c\u2019est pourquoi la r\u00e9introduction d\u2019un service sanitaire li\u00e9 aux constructions dans la protection civile doit \u00eatre examin\u00e9e conjointement par la Conf\u00e9d\u00e9ration et les cantons. Un rapport idoine devra \u00eatre soumis \u00e0 la prochaine conf\u00e9rence annuelle de la CG MPS, en mai 2019. La CG MPS souligne toutefois que la r\u00e9introduction du service sanitaire dans la protection civile est quasiment impossible dans la situation actuelle des effectifs de la protection civile.<\/p>\n<p>Les ouvrages de protection, compos\u00e9s de constructions prot\u00e9g\u00e9es et d\u2019abris publics, comportent eux aussi des d\u00e9fis aujourd\u2019hui. L\u2019OFPP entend \u00e9laborer une strat\u00e9gie globale pour les ouvrages prot\u00e9g\u00e9s. Outre le besoin, il s\u2019agira de tenir compte aussi d\u2019aspects topographiques, g\u00e9ographiques et politiques. Dans la mesure o\u00f9 cela est indiqu\u00e9, les ouvrages de protection exc\u00e9dentaires devraient \u00eatre r\u00e9affect\u00e9s en vue de l\u2019accomplissement d\u2019autres t\u00e2ches de la protection de la population, par exemple en abris publics. Il est pr\u00e9vu de faire un \u00e9tat des lieux, de d\u00e9finir des crit\u00e8res de s\u00e9lection et de concr\u00e9tiser les planifications de besoins, le tout en collaboration avec les cantons. La CG MPS a pris connaissance des activit\u00e9s pr\u00e9vues.<\/p>\n<p>Le conseiller f\u00e9d\u00e9ral Guy Parmelin, chef du DDPS, a inform\u00e9 les membres de la CG MPS sur des th\u00e8mes d\u2019actualit\u00e9 relevant de la politique de s\u00e9curit\u00e9 et de la protection de la population. Le vice-directeur du Service de renseignement de la Conf\u00e9d\u00e9ration (SRC) a pris position au sujet des menaces les plus actuelles en relation avec la politique de s\u00e9curit\u00e9. Le commandant de corps Philippe Rebord, chef de l\u2019arm\u00e9e, a inform\u00e9 sur l\u2019\u00e9tat actuel de la mise en \u0153uvre du DEVA. M. Benno B\u00fchlmann, directeur de l&rsquo;OFPP, a inform\u00e9 sur les principaux d\u00e9fis pour la protection de la population.<\/p>\n<p>L\u2019assembl\u00e9e pl\u00e9ni\u00e8re a \u00e9lu comme nouveau vice-pr\u00e9sident le conseiller d\u2019Etat Paul Winiker, de Lucerne. Il succ\u00e8de ainsi au conseiller d\u2019Etat grison Christian Rathgeb, qui a quitt\u00e9 le comit\u00e9 \u00e0 la fin 2017.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019assembl\u00e9e annuelle de la Conf\u00e9rence gouvernementale intercantonale des affaires militaires, de la protection civile et des sapeurs-pompiers (CG MPS)\u00a0du 4 mai 2018 \u00e0 l&rsquo; Abbaye b\u00e9n\u00e9dictine de Disentis a notamment \u00e9t\u00e9 consacr\u00e9e \u00e0 la prise de d\u00e9cision au sujet de l\u2019introduction d\u2019une journ\u00e9e d\u2019information obligatoire pour les Suissesses et \u00e0 la clarification de t\u00e2ches en [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-873","post","type-post","status-publish","format-standard","hentry","category-non-classifiee"],"_links":{"self":[{"href":"https:\/\/tst.rkmzf.ch\/fr\/wp-json\/wp\/v2\/posts\/873","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tst.rkmzf.ch\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tst.rkmzf.ch\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tst.rkmzf.ch\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/tst.rkmzf.ch\/fr\/wp-json\/wp\/v2\/comments?post=873"}],"version-history":[{"count":1,"href":"https:\/\/tst.rkmzf.ch\/fr\/wp-json\/wp\/v2\/posts\/873\/revisions"}],"predecessor-version":[{"id":874,"href":"https:\/\/tst.rkmzf.ch\/fr\/wp-json\/wp\/v2\/posts\/873\/revisions\/874"}],"wp:attachment":[{"href":"https:\/\/tst.rkmzf.ch\/fr\/wp-json\/wp\/v2\/media?parent=873"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tst.rkmzf.ch\/fr\/wp-json\/wp\/v2\/categories?post=873"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tst.rkmzf.ch\/fr\/wp-json\/wp\/v2\/tags?post=873"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}